{"id":85047,"date":"2026-07-14T13:10:09","date_gmt":"2026-07-14T11:10:09","guid":{"rendered":"https:\/\/petronor.eus\/?p=85047"},"modified":"2026-07-14T13:10:10","modified_gmt":"2026-07-14T11:10:10","slug":"confebaskek-eta-ceoek-bisitatu-dute-petronor","status":"publish","type":"post","link":"https:\/\/petronor.eus\/eu\/2026\/07\/confebaskek-eta-ceoek-bisitatu-dute-petronor\/","title":{"rendered":"Confebaskek eta CEOEk bisitatu dute Petronor"},"content":{"rendered":"\n<p>Berrikuntza teknologikoak eta bektore energetiko berrien garapenak industria eraldatzeko eta honen lehiakortasunari eta enpleguari eusteko duen gaitasuna ezagutzea izan da bisitaren helburua.<\/p>\n\n\n\n<p>Jose Ignacio Zudaire eta Aitor Arzuaga ondoan zituztela, bertaratutakoek findegiko instalazioak bisitatu eta bertatik bertara ezagutu dituzte konpainiaren deskarbonizazio-estrategia eta erregai gero eta berriztagarriagoak ekoizteko bultzatzen ari den ekintzak. Era berean, 2,5 MWeko elektrolizagailua bisitatu dute, 2023ko urrian martxan jarri eta geroztik hidrogeno berriztagarria sortzeko aukera ematen duen Euskadiko lehena.<\/p>\n","protected":false},"excerpt":{"rendered":"Ingurumenari buruzko Lurralde Koordinaziorako XI. Foroaren barruan, profesional-talde batek, Confebask eta CEOEko kideak tarteko, Euskadiko industria-eraldaketaren eta trantsizio energetikoaren erreferentziazko ekimen bihurtu diren <strong>Petronorren <\/strong>Muskizko instalazioak bisitatu ditu. ","protected":false},"author":5,"featured_media":85043,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[70],"tags":[118,120],"class_list":["post-85047","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-albisteak","tag-findegia","tag-petronor"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Confebaskek eta CEOEk bisitatu dute Petronor - Petronor<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/petronor.eus\/eu\/2026\/07\/confebaskek-eta-ceoek-bisitatu-dute-petronor\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Confebaskek eta CEOEk bisitatu dute Petronor - Petronor\" \/>\n<meta property=\"og:description\" content=\"Ingurumenari buruzko Lurralde Koordinaziorako XI. Foroaren barruan, profesional-talde batek, Confebask eta CEOEko kideak tarteko, Euskadiko industria-eraldaketaren eta trantsizio energetikoaren erreferentziazko ekimen bihurtu diren Petronorren Muskizko instalazioak bisitatu ditu.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/petronor.eus\/eu\/2026\/07\/confebaskek-eta-ceoek-bisitatu-dute-petronor\/\" \/>\n<meta property=\"og:site_name\" content=\"Petronor\" \/>\n<meta property=\"article:published_time\" content=\"2026-07-14T11:10:09+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-14T11:10:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/petronor.eus\/wp-content\/uploads\/2026\/07\/EUG1125.JPG-scaled.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1707\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Petronor User\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Petronor User\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minutua\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/petronor.eus\/eu\/2026\/07\/confebaskek-eta-ceoek-bisitatu-dute-petronor\/\",\"url\":\"https:\/\/petronor.eus\/eu\/2026\/07\/confebaskek-eta-ceoek-bisitatu-dute-petronor\/\",\"name\":\"Confebaskek eta CEOEk bisitatu dute Petronor - Petronor\",\"isPartOf\":{\"@id\":\"https:\/\/petronor.eus\/es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/petronor.eus\/eu\/2026\/07\/confebaskek-eta-ceoek-bisitatu-dute-petronor\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/petronor.eus\/eu\/2026\/07\/confebaskek-eta-ceoek-bisitatu-dute-petronor\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/petronor.eus\/wp-content\/uploads\/2026\/07\/EUG1125.JPG-scaled.jpeg\",\"datePublished\":\"2026-07-14T11:10:09+00:00\",\"dateModified\":\"2026-07-14T11:10:10+00:00\",\"author\":{\"@id\":\"https:\/\/petronor.eus\/es\/#\/schema\/person\/fd6bd800e1733647d78fbc4108fd4a92\"},\"breadcrumb\":{\"@id\":\"https:\/\/petronor.eus\/eu\/2026\/07\/confebaskek-eta-ceoek-bisitatu-dute-petronor\/#breadcrumb\"},\"inLanguage\":\"eu\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/petronor.eus\/eu\/2026\/07\/confebaskek-eta-ceoek-bisitatu-dute-petronor\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"eu\",\"@id\":\"https:\/\/petronor.eus\/eu\/2026\/07\/confebaskek-eta-ceoek-bisitatu-dute-petronor\/#primaryimage\",\"url\":\"https:\/\/petronor.eus\/wp-content\/uploads\/2026\/07\/EUG1125.JPG-scaled.jpeg\",\"contentUrl\":\"https:\/\/petronor.eus\/wp-content\/uploads\/2026\/07\/EUG1125.JPG-scaled.jpeg\",\"width\":2560,\"height\":1707},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/petronor.eus\/eu\/2026\/07\/confebaskek-eta-ceoek-bisitatu-dute-petronor\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/petronor.eus\/eu\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Confebaskek eta CEOEk bisitatu dute Petronor\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/petronor.eus\/es\/#website\",\"url\":\"https:\/\/petronor.eus\/es\/\",\"name\":\"Petronor\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/petronor.eus\/es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"eu\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/petronor.eus\/es\/#\/schema\/person\/fd6bd800e1733647d78fbc4108fd4a92\",\"name\":\"Petronor User\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"eu\",\"@id\":\"https:\/\/petronor.eus\/es\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/b58c6f14d292556214bd64909bcdb118?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/b58c6f14d292556214bd64909bcdb118?s=96&d=mm&r=g\",\"caption\":\"Petronor User\"},\"url\":\"https:\/\/petronor.eus\/eu\/author\/petronor_us\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Confebaskek eta CEOEk bisitatu dute Petronor - Petronor","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/petronor.eus\/eu\/2026\/07\/confebaskek-eta-ceoek-bisitatu-dute-petronor\/","og_locale":"en_US","og_type":"article","og_title":"Confebaskek eta CEOEk bisitatu dute Petronor - Petronor","og_description":"Ingurumenari buruzko Lurralde Koordinaziorako XI. Foroaren barruan, profesional-talde batek, Confebask eta CEOEko kideak tarteko, Euskadiko industria-eraldaketaren eta trantsizio energetikoaren erreferentziazko ekimen bihurtu diren Petronorren Muskizko instalazioak bisitatu ditu.","og_url":"https:\/\/petronor.eus\/eu\/2026\/07\/confebaskek-eta-ceoek-bisitatu-dute-petronor\/","og_site_name":"Petronor","article_published_time":"2026-07-14T11:10:09+00:00","article_modified_time":"2026-07-14T11:10:10+00:00","og_image":[{"width":2560,"height":1707,"url":"https:\/\/petronor.eus\/wp-content\/uploads\/2026\/07\/EUG1125.JPG-scaled.jpeg","type":"image\/jpeg"}],"author":"Petronor User","twitter_misc":{"Written by":"Petronor User","Est. reading time":"1 minutua"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/petronor.eus\/eu\/2026\/07\/confebaskek-eta-ceoek-bisitatu-dute-petronor\/","url":"https:\/\/petronor.eus\/eu\/2026\/07\/confebaskek-eta-ceoek-bisitatu-dute-petronor\/","name":"Confebaskek eta CEOEk bisitatu dute Petronor - Petronor","isPartOf":{"@id":"https:\/\/petronor.eus\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/petronor.eus\/eu\/2026\/07\/confebaskek-eta-ceoek-bisitatu-dute-petronor\/#primaryimage"},"image":{"@id":"https:\/\/petronor.eus\/eu\/2026\/07\/confebaskek-eta-ceoek-bisitatu-dute-petronor\/#primaryimage"},"thumbnailUrl":"https:\/\/petronor.eus\/wp-content\/uploads\/2026\/07\/EUG1125.JPG-scaled.jpeg","datePublished":"2026-07-14T11:10:09+00:00","dateModified":"2026-07-14T11:10:10+00:00","author":{"@id":"https:\/\/petronor.eus\/es\/#\/schema\/person\/fd6bd800e1733647d78fbc4108fd4a92"},"breadcrumb":{"@id":"https:\/\/petronor.eus\/eu\/2026\/07\/confebaskek-eta-ceoek-bisitatu-dute-petronor\/#breadcrumb"},"inLanguage":"eu","potentialAction":[{"@type":"ReadAction","target":["https:\/\/petronor.eus\/eu\/2026\/07\/confebaskek-eta-ceoek-bisitatu-dute-petronor\/"]}]},{"@type":"ImageObject","inLanguage":"eu","@id":"https:\/\/petronor.eus\/eu\/2026\/07\/confebaskek-eta-ceoek-bisitatu-dute-petronor\/#primaryimage","url":"https:\/\/petronor.eus\/wp-content\/uploads\/2026\/07\/EUG1125.JPG-scaled.jpeg","contentUrl":"https:\/\/petronor.eus\/wp-content\/uploads\/2026\/07\/EUG1125.JPG-scaled.jpeg","width":2560,"height":1707},{"@type":"BreadcrumbList","@id":"https:\/\/petronor.eus\/eu\/2026\/07\/confebaskek-eta-ceoek-bisitatu-dute-petronor\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/petronor.eus\/eu\/"},{"@type":"ListItem","position":2,"name":"Confebaskek eta CEOEk bisitatu dute Petronor"}]},{"@type":"WebSite","@id":"https:\/\/petronor.eus\/es\/#website","url":"https:\/\/petronor.eus\/es\/","name":"Petronor","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/petronor.eus\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"eu"},{"@type":"Person","@id":"https:\/\/petronor.eus\/es\/#\/schema\/person\/fd6bd800e1733647d78fbc4108fd4a92","name":"Petronor User","image":{"@type":"ImageObject","inLanguage":"eu","@id":"https:\/\/petronor.eus\/es\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/b58c6f14d292556214bd64909bcdb118?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b58c6f14d292556214bd64909bcdb118?s=96&d=mm&r=g","caption":"Petronor User"},"url":"https:\/\/petronor.eus\/eu\/author\/petronor_us\/"}]}},"_links":{"self":[{"href":"https:\/\/petronor.eus\/eu\/wp-json\/wp\/v2\/posts\/85047","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/petronor.eus\/eu\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/petronor.eus\/eu\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/petronor.eus\/eu\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/petronor.eus\/eu\/wp-json\/wp\/v2\/comments?post=85047"}],"version-history":[{"count":2,"href":"https:\/\/petronor.eus\/eu\/wp-json\/wp\/v2\/posts\/85047\/revisions"}],"predecessor-version":[{"id":85049,"href":"https:\/\/petronor.eus\/eu\/wp-json\/wp\/v2\/posts\/85047\/revisions\/85049"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/petronor.eus\/eu\/wp-json\/wp\/v2\/media\/85043"}],"wp:attachment":[{"href":"https:\/\/petronor.eus\/eu\/wp-json\/wp\/v2\/media?parent=85047"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/petronor.eus\/eu\/wp-json\/wp\/v2\/categories?post=85047"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/petronor.eus\/eu\/wp-json\/wp\/v2\/tags?post=85047"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}